{"id":20725,"date":"2008-09-14T12:54:28","date_gmt":"2008-09-14T10:54:28","guid":{"rendered":"https:\/\/www.estudidelmoble.com\/producte\/publicacion-3-2008\/"},"modified":"2021-04-22T18:32:32","modified_gmt":"2021-04-22T16:32:32","slug":"publicacion-3-2008","status":"publish","type":"product","link":"https:\/\/www.estudidelmoble.com\/es\/producto\/publicacion-3-2008\/","title":{"rendered":"PUBLICACI\u00d3N 3"},"content":{"rendered":"<p><span style=\"font-weight: 400\">La Primera Jornada T\u00e9cnica sobre Criterios de Conservaci\u00f3n y Restauraci\u00f3n de Mobiliario es una publicaci\u00f3n clave ya que responde a una preocupaci\u00f3n por el estado del patrimonio en muebles y por la situaci\u00f3n de los profesionales que ejercen la restauraci\u00f3n, as\u00ed como a la voluntad de mejorar la calidad de las intervenciones que se llevan a cabo en los muebles.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Cuando entramos en las casas o en los museos con el objetivo de estudiar, catalogar <\/span><span style=\"font-weight: 400\">o conocer alguna colecci\u00f3n de muebles, habitualmente nos llama la atenci\u00f3n el mal estado <\/span><span style=\"font-weight: 400\">de las piezas, en algunas ocasiones debido a su falta de cuidado y en otras a las malas <\/span><span style=\"font-weight: 400\">intervenciones, muchas veces llevadas a cabo por personas no especializadas en la restauraci\u00f3n de mobiliario.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Efectivamente, la conservaci\u00f3n y la restauraci\u00f3n del mueble presentan una problem\u00e1tica <\/span><span style=\"font-weight: 400\">compleja, pero no por ello no mejorable, que debe ser tenida en cuenta a la hora <\/span><span style=\"font-weight: 400\">de buscar soluciones. Parte de esta complejidad es compartida por otras ramas del patrimonio, pero en el caso del mueble se agrava por la falta de iniciativas que ayuden a marcar pautas de actuaci\u00f3n. En esta jornada se pretendi\u00f3 crear una ruta de actuaci\u00f3n que ayudar\u00e1 a marcar unos compromisos. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span style=\"color: #7f2629\"><strong><b>Primera Jornada t\u00e9cnica sobre criterios de conservaci\u00f3n y restauraci\u00f3n de mobiliario<\/b><\/strong><\/span><\/p>\n<p class=\"p1\">Edici\u00f3n castellano<\/p>\n<p><strong>PVP: 18\u20ac<br \/>Precio SOCIOS: 15\u20ac<\/strong><\/p>\n","protected":false},"featured_media":19881,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[833],"product_tag":[],"class_list":["post-20725","product","type-product","status-publish","has-post-thumbnail","product_cat-publicaciones","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/product\/20725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/product\/20725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/media\/19881"}],"wp:attachment":[{"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/media?parent=20725"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/product_brand?post=20725"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/product_cat?post=20725"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.estudidelmoble.com\/es\/wp-json\/wp\/v2\/product_tag?post=20725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}